{"id":13084,"date":"2026-03-18T11:56:50","date_gmt":"2026-03-18T09:56:50","guid":{"rendered":"https:\/\/prueba.fundacionginer.org\/?post_type=actividades&#038;p=13084"},"modified":"2026-04-16T12:32:18","modified_gmt":"2026-04-16T10:32:18","slug":"colonias-urbanas-cientificas-2026","status":"publish","type":"actividades","link":"https:\/\/prueba.fundacionginer.org\/en\/actividades\/colonias-urbanas-cientificas-2026\/","title":{"rendered":"Scientific urban camps"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><section class=\"vc_row wpb_row vc_row-fluid vc_custom_1666273406542 liquid-row-shadowbox-6a04b1893fc5a\"><div class=\"ld-container container\"><div class=\"row ld-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 liquid-column-6a04b1893ff31\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"   ><div class=\"wpb_wrapper-inner\"><style>@media (min-width: 1200px) { .liquid-row-responsive-6a04b18940076 {margin-top:-20px !important;  }  }  <\/style><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666274032498 liquid-row-responsive-6a04b18940076 liquid-row-shadowbox-6a04b18940087\"><div class=\"wpb_column vc_column_container vc_col-sm-6 liquid-column-6a04b1894026b\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper vc_custom_1666274090693\"  ><div class=\"wpb_wrapper-inner\"><style>.ld_icon_box_6a04b18941b7d .iconbox-icon-container{color:rgb(0, 0, 0);font-size:20px;border-radius:px;}.ld_icon_box_6a04b18941b7d h3{margin-bottom:1px;}<\/style>\n<div class=\"iconbox iconbox-inline ld_icon_box_6a04b18941b7d vc_custom_1695123451310\" id=\"ld_icon_box_6a04b18941b7d\"  data-plugin-options='{\"color\":\"rgb(0, 0, 0)\"}'  >\n\t\n\t\t<div class=\"iconbox-icon-wrap\"><span class=\"iconbox-icon-container\"><i class=\"icon-basic_calendar\"><\/i><\/span><\/div><!-- \/.iconbox-icon-wrap -->\t\n\t<h3>Date<\/h3>\t\n\t\t\n\t\t\t\t\n\t\t\n\t\n<\/div>\n<div class=\"vc_acf vc_txt_align_left field_6353db0d6064b\">March and April 2026<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 liquid-column-6a04b18942cd3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"  ><div class=\"wpb_wrapper-inner\"><style>.ld_icon_box_6a04b18942d8b .iconbox-icon-container{color:rgb(0, 0, 0);font-size:20px;border-radius:px;}.ld_icon_box_6a04b18942d8b h3{margin-bottom:1px;}<\/style>\n<div class=\"iconbox iconbox-inline ld_icon_box_6a04b18942d8b vc_custom_1743853217151\" id=\"ld_icon_box_6a04b18942d8b\"  data-plugin-options='{\"color\":\"rgb(0, 0, 0)\"}'  >\n\t\n\t\t<div class=\"iconbox-icon-wrap\"><span class=\"iconbox-icon-container\"><i class=\"icon-et-notebook\"><\/i><\/span><\/div><!-- \/.iconbox-icon-wrap -->\t\n\t<h3>Organizers<\/h3>\t\n\t\t\n\t\t\t\t\n\t\t\n\t\n<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Instituci\u00f3n Libre de Ense\u00f1anza y Corporaci\u00f3n de Antiguos Alumnos y Amigos de la ILE<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><style>@media (min-width: 1200px) { .liquid-row-responsive-6a04b18943906 {margin-top:0px !important;  }  }  <\/style><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666274134962 liquid-row-responsive-6a04b18943906 liquid-row-shadowbox-6a04b18943918 vc_row-o-equal-height vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12 liquid-column-6a04b18943ace\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper vc_custom_1666274095109\"  ><div class=\"wpb_wrapper-inner\"><style>.ld_icon_box_6a04b18943bbd .iconbox-icon-container{color:rgb(0, 0, 0);font-size:20px;border-radius:px;}.ld_icon_box_6a04b18943bbd h3{margin-bottom:1px;}<\/style>\n<div class=\"iconbox iconbox-inline ld_icon_box_6a04b18943bbd vc_custom_1666273898910\" id=\"ld_icon_box_6a04b18943bbd\"  data-plugin-options='{\"color\":\"rgb(0, 0, 0)\"}'  >\n\t\n\t\t<div class=\"iconbox-icon-wrap\"><span class=\"iconbox-icon-container\"><i class=\"icon-basic_geolocalize-01\"><\/i><\/span><\/div><!-- \/.iconbox-icon-wrap -->\t\n\t<h3>Location<\/h3>\t\n\t\t\n\t\t\t\t\n\t\t\n\t\n<\/div>\n<div class=\"vc_acf vc_txt_align_left field_6353dde259aba\">Instituci\u00f3n Libre de Ense\u00f1anza, P.\u00ba General Mart\u00ednez Campos, 14. 28010 - Madrid<\/div><div class=\"vc_empty_space\"   style=\"height: 24px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><style>.ld_icon_box_6a04b18944798 .iconbox-icon-container{color:rgb(0, 0, 0);font-size:20px;border-radius:px;}.ld_icon_box_6a04b18944798 h3{margin-bottom:1px;}<\/style>\n<div class=\"iconbox iconbox-inline ld_icon_box_6a04b18944798 vc_custom_1701339772147\" id=\"ld_icon_box_6a04b18944798\"  data-plugin-options='{\"color\":\"rgb(0, 0, 0)\"}'  >\n\t\n\t\t<div class=\"iconbox-icon-wrap\"><span class=\"iconbox-icon-container\"><i class=\"icon-et-document\"><\/i><\/span><\/div><!-- \/.iconbox-icon-wrap -->\t\n\t<h3>Collaborate<\/h3>\t\n\t\t\n\t\t\t\t\n\t\t\n\t\n<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><img decoding=\"async\" class=\"alignnone wp-image-12715\" src=\"http:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/MCIU.Gob_.Web-72px.png\" alt=\"\" width=\"179\" height=\"45\" srcset=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/MCIU.Gob_.Web-72px.png 286w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/MCIU.Gob_.Web-72px-18x5.png 18w\" sizes=\"(max-width: 179px) 100vw, 179px\" \/>\u00a0 <img decoding=\"async\" class=\"alignnone wp-image-12716\" src=\"http:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/logos-clientes-Fecyt_600-300x150.png\" alt=\"\" width=\"130\" height=\"65\" srcset=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/logos-clientes-Fecyt_600-300x150.png 300w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/logos-clientes-Fecyt_600-18x9.png 18w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/logos-clientes-Fecyt_600.png 600w\" sizes=\"(max-width: 130px) 100vw, 130px\" \/> <img decoding=\"async\" class=\"alignnone wp-image-12717\" src=\"http:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/logo_sello-de-patrimonio-europeo-300x199.jpg\" alt=\"\" width=\"136\" height=\"90\" srcset=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/logo_sello-de-patrimonio-europeo-300x199.jpg 300w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/logo_sello-de-patrimonio-europeo-18x12.jpg 18w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/logo_sello-de-patrimonio-europeo.jpg 400w\" sizes=\"(max-width: 136px) 100vw, 136px\" \/>. <img decoding=\"async\" class=\"alignnone wp-image-12719\" src=\"http:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/Logo-de-la-ILE4-300x157.jpg\" alt=\"\" width=\"107\" height=\"56\" srcset=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/Logo-de-la-ILE4-300x157.jpg 300w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/Logo-de-la-ILE4-1024x537.jpg 1024w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/Logo-de-la-ILE4-18x9.jpg 18w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/01\/Logo-de-la-ILE4.jpg 1240w\" sizes=\"(max-width: 107px) 100vw, 107px\" \/> \u00a0<img decoding=\"async\" class=\"alignnone wp-image-12217\" src=\"http:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-06-04-a-las-17.26.48-300x61.png\" alt=\"\" width=\"187\" height=\"38\" srcset=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-06-04-a-las-17.26.48-300x61.png 300w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-06-04-a-las-17.26.48-18x4.png 18w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-06-04-a-las-17.26.48.png 722w\" sizes=\"(max-width: 187px) 100vw, 187px\" \/> \u00a0<img decoding=\"async\" class=\"alignnone wp-image-11959\" src=\"http:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2024\/02\/Penalara.jpg\" alt=\"\" width=\"96\" height=\"96\" srcset=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2024\/02\/Penalara.jpg 294w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2024\/02\/Penalara-150x150.jpg 150w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2024\/02\/Penalara-12x12.jpg 12w\" sizes=\"(max-width: 96px) 100vw, 96px\" \/>\u00a0 \u00a0 <img decoding=\"async\" class=\"alignnone wp-image-13093\" src=\"http:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/unnamed-300x115.png\" alt=\"\" width=\"138\" height=\"53\" srcset=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/unnamed-300x115.png 300w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/unnamed-18x7.png 18w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/unnamed.png 512w\" sizes=\"(max-width: 138px) 100vw, 138px\" \/><img decoding=\"async\" class=\"alignnone wp-image-13094\" src=\"http:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/logos-organizadores-csic-600x390-1-300x195.jpg\" alt=\"\" width=\"151\" height=\"98\" srcset=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/logos-organizadores-csic-600x390-1-300x195.jpg 300w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/logos-organizadores-csic-600x390-1-18x12.jpg 18w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/logos-organizadores-csic-600x390-1.jpg 600w\" sizes=\"(max-width: 151px) 100vw, 151px\" \/> \u00a0<img decoding=\"async\" class=\"alignnone wp-image-13095\" src=\"http:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/imidra_fondo_transparente_2-300x86.png\" alt=\"\" width=\"160\" height=\"46\" srcset=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/imidra_fondo_transparente_2-300x86.png 300w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/imidra_fondo_transparente_2-1024x293.png 1024w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/imidra_fondo_transparente_2-18x5.png 18w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/imidra_fondo_transparente_2.png 1920w\" sizes=\"(max-width: 160px) 100vw, 160px\" \/><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"vc_row wpb_row vc_row-fluid liquid-row-shadowbox-6a04b18944c17 vc_column-gap-35\"><div class=\"ld-container container\"><div class=\"row ld-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 liquid-column-6a04b18944e54\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"   ><div class=\"wpb_wrapper-inner\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong><span style=\"font-size: 18px;\">Children activities, directed towards children of ages 7-12 years.<\/span><\/strong><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 24px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_tta-container\" data-vc-action=\"collapseAll\"><div class=\"vc_general vc_tta vc_tta-accordion vc_tta-color-black vc_tta-style-outline vc_tta-shape-square vc_tta-o-shape-group vc_tta-controls-align-default vc_tta-o-all-clickable\"><div class=\"vc_tta-panels-container\"><div class=\"vc_tta-panels\"><div class=\"vc_tta-panel\" id=\"ld-1743773546706-c44c565d-461d\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><p class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#ld-1743773546706-c44c565d-461d\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Cavalry stone excursion: geological route through La Pedriza (27th of March)<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/p><\/div><div class=\"vc_tta-panel-body\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666605409994 liquid-row-shadowbox-6a04b18945213\"><div class=\"wpb_column vc_column_container vc_col-sm-12 liquid-column-6a04b18945389\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"  ><div class=\"wpb_wrapper-inner\"><div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>Fecha:<\/strong> Viernes, 27 de marzo.<br \/>\n<strong>Horario:<\/strong> Entrada flexible de 8.05 a 9.05 h. Vuelta a las 16.30 h.<br \/>\n<strong>Lugar de encuentro:<\/strong> Instituci\u00f3n Libre de Ense\u00f1anza. Paseo del General Mart\u00ednez Campos, 14. 28010 Madrid.<\/p>\n<p>Docentes:<br \/>\n<strong>Alba Garc\u00eda y Jaime Sebasti\u00e1n<\/strong><br \/>\nGu\u00edas int\u00e9rpretes del Parque Nacional Sierra de Guadarrama y colaboradores de la vocal\u00eda de Medioambiente de la RSEA Pe\u00f1alara.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>La Pedriza es un lugar con mucha historia y lleno de secretos. Aqu\u00ed se encuentran formaciones rocosas con nombre propio como el Yelmo, la Tortuga, el Dinosaurio, el Indio y el C\u00e1liz, entre otras muchas. A trav\u00e9s de un paseo por bosques y laberintos de domos gran\u00edticos, descubriremos c\u00f3mo se han formado estas maravillas de la geolog\u00eda. Desde el coraz\u00f3n del Parque Nacional de la Sierra de Guadarrama, nos dejaremos inspirar por sus leyendas y, con la ayuda de nuestra imaginaci\u00f3n, podremos averiguar algunos de sus secretos.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Distancia a recorrer:<\/b><span style=\"font-weight: 400;\"> 5,5 km, aproximadamente.<\/span><\/p>\n<p><b>Imprescindible llevar:<\/b><span style=\"font-weight: 400;\"> comida y agua (comeremos en el campo), ropa y calzado adecuado (en los d\u00edas previos a la salida, se recomendar\u00e1 de forma m\u00e1s espec\u00edfica en funci\u00f3n del pron\u00f3stico del tiempo).<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"ld-1774001481392-e1bdeaf3-14f3\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><p class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#ld-1774001481392-e1bdeaf3-14f3\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Learn science\/ Make science with the National Museum of Natural Sciences (30th, 31st of March and 1st of April)<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/p><\/div><div class=\"vc_tta-panel-body\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666605409994 liquid-row-shadowbox-6a04b1894689d\"><div class=\"wpb_column vc_column_container vc_col-sm-12 liquid-column-6a04b18946a51\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"  ><div class=\"wpb_wrapper-inner\"><div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>Horario:<\/strong> Entrada flexible, de 8.05 a 9.05 h. Salida flexible, de 14.00 a 15.00 h<\/p>\n<p><strong>Lugar de encuentro: <\/strong>RESIDENCIA DE ESTUDIANTES Calle del Pinar, 21. 28006 Madrid<\/p>\n<p><strong>Docentes:<\/strong><br \/>\nItziar D\u00edaz-Delgado y educadores ambientales del Museo Nacional de Ciencias Naturales (MNCN-CSIC)<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Lunes, 30 marzo<\/b><\/p>\n<p><i><span style=\"font-weight: 400;\">Taller y visita al Museo de Ciencias Naturales Reino animal al detalle:<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">A trav\u00e9s de claves dicot\u00f3micas, el Museo de Ciencias Naturales nos acercar\u00e1 al mundo de la taxonom\u00eda, trabajando con ejemplares reales de las colecciones de invertebrados y vertebrados preservados mediante distintas t\u00e9cnicas de conservaci\u00f3n.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Martes, 31 marzo<\/b><\/p>\n<p><i><span style=\"font-weight: 400;\">Taller y visita al Museo de Ciencias Naturales Insectos: peque\u00f1os gigantes:\u00a0<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Mediante la visita al Museo y un taller pr\u00e1ctico, trabajaremos con distintas especies de insectos, gracias a las colecciones que all\u00ed se albergan. Descubriremos su gran diversidad y c\u00f3mo se han adaptado al medio que habitan.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Mi\u00e9rcoles, 1 abril\u00a0<\/b><\/p>\n<p><i><span style=\"font-weight: 400;\">Taller y visita al Museo de Ciencias Naturales El cuerpo: un puzle en movimiento:<\/span><\/i><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El esqueleto humano tiene m\u00e1s de 2000 huesos y cada uno de ellos tiene una colocaci\u00f3n espec\u00edfica, \u00bfseremos capaces de saber cu\u00e1l es? Con esta visita al Museo, no solo descubriremos los secretos del cuerpo humano, sino que tambi\u00e9n lo compararemos con el de otros animales para experimentar el porqu\u00e9 de esa colocaci\u00f3n tan espec\u00edfica y las adaptaciones de los distintos vertebrados.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"ld-1774001905743-40d00300-68f5\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><p class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#ld-1774001905743-40d00300-68f5\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Workshop in the ILE: the biodiversity in foods (6th of April)<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/p><\/div><div class=\"vc_tta-panel-body\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666605409994 liquid-row-shadowbox-6a04b18947132\"><div class=\"wpb_column vc_column_container vc_col-sm-12 liquid-column-6a04b18947295\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"  ><div class=\"wpb_wrapper-inner\"><div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>Fecha:<\/strong> Lunes, 6 de abril.<br \/>\n<strong>Horario:<\/strong> Entrada flexible de 8.05 a 9.05 h. Vuelta a las 16.30 h.<br \/>\n<strong>Lugar de encuentro:<\/strong> Instituci\u00f3n Libre de Ense\u00f1anza. Paseo del General Mart\u00ednez Campos, 14. 28010 Madrid.<\/p>\n<p>Docentes:<br \/>\n<strong>Remedios Alarc\u00f3n V\u00edllora <\/strong><br \/>\nInvestigadora en el Instituto Madrile\u00f1o de Investigaci\u00f3n y Desarrollo Rural, Agrario y Alimentario &#8211; IMIDRA<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>La agrodiversidad hace referencia a la biodiversidad de los cultivos que alimentan a la humanidad, los cuales var\u00edan seg\u00fan los diferentes ambientes de clima y la tipolog\u00eda de los suelos. Pondremos especial atenci\u00f3n en la identificaci\u00f3n de algunas caracter\u00edsticas de las plantas, por ejemplo, el tama\u00f1o de sus semillas o de sus hojas, que pueden indicarnos c\u00f3mo es el entorno donde se cultivan. Tambi\u00e9n descubriremos por qu\u00e9 la diversidad en las especies es \u00fatil para la humanidad.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><style>@media (min-width: 1200px) { .liquid-row-responsive-6a04b1894867f {margin-top:30px !important;  }  }   <\/style><section data-bg-image=\"url\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1684786317639 row-contains-padding-top liquid-row-responsive-6a04b1894867f liquid-row-shadowbox-6a04b18948696 vc_row-has-fill vc_row-has-bg\"><div class=\"ld-container container\"><div class=\"row ld-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 liquid-column-6a04b189488b6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"   ><div class=\"wpb_wrapper-inner\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1743584411331\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>MORE INFORMATION AND REGISTRATION<\/strong><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1743853336066\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Silvia Basanta \/ Itziar Diaz-Delgado<br \/>\n<\/span><a href=\"tel:626682218\">626 682 218<\/a>\u00a0 \u00a0&#8211; \u00a0 <a href=\"mailto:escueledetiempolibre@fundacionginer.com\">escueledetiempolibre@fundacionginer.com<\/a><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1743853400955\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>REGISTRATION FEE<\/strong><i><\/i><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1774002021658\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">One Activity: \u20ac25<br \/>\n<\/span><span style=\"font-weight: 400;\">The five activities: \u20ac100\u00a0<\/span><\/p>\n<p><span style=\"font-size: 14px;\"><i><span style=\"font-weight: 400;\">50% discount for the members of the cooperation of old students and friends of the ILE and friends of Residencia of Estudiantes. Possible free places for children in vulnerability and\/or with a credited disability. Consult conditions.<br \/>\n<\/span><\/i><\/span><\/p>\n<p><b>Limited spaces.<\/b><span style=\"font-weight: 400;\">There will be preference to who signs up for the five activities all together until the 15th of March.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 30px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n<\/div>","protected":false},"featured_media":13118,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[116,113],"tags":[78],"class_list":["post-13084","actividades","type-actividades","status-publish","format-standard","has-post-thumbnail","hentry","category-colonias-urbanas","category-naturaleza","tag-pasadas"],"acf":[],"_links":{"self":[{"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/actividades\/13084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/actividades"}],"about":[{"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/types\/actividades"}],"version-history":[{"count":21,"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/actividades\/13084\/revisions"}],"predecessor-version":[{"id":13088,"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/actividades\/13084\/revisions\/13088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/media\/13118"}],"wp:attachment":[{"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/media?parent=13084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/categories?post=13084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/tags?post=13084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}