{"id":13067,"date":"2026-03-20T11:33:35","date_gmt":"2026-03-20T09:33:35","guid":{"rendered":"https:\/\/prueba.fundacionginer.org\/?post_type=actividades&#038;p=13067"},"modified":"2026-04-15T13:45:30","modified_gmt":"2026-04-15T11:45:30","slug":"colonias-de-vacaciones-de-la-ile-2026","status":"publish","type":"actividades","link":"https:\/\/prueba.fundacionginer.org\/en\/actividades\/colonias-de-vacaciones-de-la-ile-2026\/","title":{"rendered":"Summer holiday camps of the ILE 2026"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><section class=\"vc_row wpb_row vc_row-fluid vc_custom_1666273406542 liquid-row-shadowbox-6a04b18dcf8fd\"><div class=\"ld-container container\"><div class=\"row ld-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 liquid-column-6a04b18dcfba3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"   ><div class=\"wpb_wrapper-inner\"><style>@media (min-width: 1200px) { .liquid-row-responsive-6a04b18dcfce6 {margin-top:-20px !important;  }  }  <\/style><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666274032498 liquid-row-responsive-6a04b18dcfce6 liquid-row-shadowbox-6a04b18dcfcf6\"><div class=\"wpb_column vc_column_container vc_col-sm-6 liquid-column-6a04b18dcfe91\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper vc_custom_1666274090693\"  ><div class=\"wpb_wrapper-inner\"><style>.ld_icon_box_6a04b18dd17dc .iconbox-icon-container{color:rgb(0, 0, 0);font-size:20px;border-radius:px;}.ld_icon_box_6a04b18dd17dc h3{margin-bottom:1px;}<\/style>\n<div class=\"iconbox iconbox-inline ld_icon_box_6a04b18dd17dc vc_custom_1696584688255\" id=\"ld_icon_box_6a04b18dd17dc\"  data-plugin-options='{\"color\":\"rgb(0, 0, 0)\"}'  >\n\t\n\t\t<div class=\"iconbox-icon-wrap\"><span class=\"iconbox-icon-container\"><i class=\"icon-basic_calendar\"><\/i><\/span><\/div><!-- \/.iconbox-icon-wrap -->\t\n\t<h3>Date<\/h3>\t\n\t\t\n\t\t\t\t\n\t\t\n\t\n<\/div>\n<div class=\"vc_acf vc_txt_align_left field_6353db0d6064b\">June to August 2026<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 liquid-column-6a04b18dd3107\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"  ><div class=\"wpb_wrapper-inner\"><style>.ld_icon_box_6a04b18dd31ba .iconbox-icon-container{color:rgb(0, 0, 0);font-size:20px;border-radius:px;}.ld_icon_box_6a04b18dd31ba h3{margin-bottom:1px;}<\/style>\n<div class=\"iconbox iconbox-inline ld_icon_box_6a04b18dd31ba vc_custom_1666273898910\" id=\"ld_icon_box_6a04b18dd31ba\"  data-plugin-options='{\"color\":\"rgb(0, 0, 0)\"}'  >\n\t\n\t\t<div class=\"iconbox-icon-wrap\"><span class=\"iconbox-icon-container\"><i class=\"icon-basic_geolocalize-01\"><\/i><\/span><\/div><!-- \/.iconbox-icon-wrap -->\t\n\t<h3>Location<\/h3>\t\n\t\t\n\t\t\t\t\n\t\t\n\t\n<\/div>\n<div class=\"vc_acf vc_txt_align_left field_6353dde259aba\">Albergue la Torre (Santiurde de Reinosa, Cantabria)<\/div><\/div><\/div><\/div><\/div><\/div><style>@media (min-width: 1200px) { .liquid-row-responsive-6a04b18dd3816 {margin-top:0px !important;  }  }  <\/style><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1666274134962 liquid-row-responsive-6a04b18dd3816 liquid-row-shadowbox-6a04b18dd3826 vc_row-o-equal-height vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-6 liquid-column-6a04b18dd3a01\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper vc_custom_1666274095109\"  ><div class=\"wpb_wrapper-inner\"><style>.ld_icon_box_6a04b18dd3aa6 .iconbox-icon-container{color:rgb(0, 0, 0);font-size:20px;border-radius:px;}.ld_icon_box_6a04b18dd3aa6 h3{margin-bottom:1px;}<\/style>\n<div class=\"iconbox iconbox-inline ld_icon_box_6a04b18dd3aa6 vc_custom_1748945634462\" id=\"ld_icon_box_6a04b18dd3aa6\"  data-plugin-options='{\"color\":\"rgb(0, 0, 0)\"}'  >\n\t\n\t\t<div class=\"iconbox-icon-wrap\"><span class=\"iconbox-icon-container\"><i class=\"icon-ecommerce_money\"><\/i><\/span><\/div><!-- \/.iconbox-icon-wrap -->\t\n\t<h3>Price<\/h3>\t\n\t\t\n\t\t\t\t\n\t\t\n\t\n<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">\u00a0950\u20ac <span style=\"font-size: 14px;\">(including transport from Madrid)<\/span><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 liquid-column-6a04b18dd3d28\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"  ><div class=\"wpb_wrapper-inner\"><style>.ld_icon_box_6a04b18dd3de6 .iconbox-icon-container{color:rgb(0, 0, 0);font-size:20px;border-radius:px;}.ld_icon_box_6a04b18dd3de6 h3{margin-bottom:1px;}<\/style>\n<div class=\"iconbox iconbox-inline ld_icon_box_6a04b18dd3de6 vc_custom_1748945690057\" id=\"ld_icon_box_6a04b18dd3de6\"  data-plugin-options='{\"color\":\"rgb(0, 0, 0)\"}'  >\n\t\n\t\t<div class=\"iconbox-icon-wrap\"><span class=\"iconbox-icon-container\"><i class=\"icon-et-document\"><\/i><\/span><\/div><!-- \/.iconbox-icon-wrap -->\t\n\t<h3>Organized<\/h3>\t\n\t\t\n\t\t\t\t\n\t\t\n\t\n<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Instituci\u00f3n Libre de Ense\u00f1anza, Corporaci\u00f3n de antiguos alumnos y amigos de la ILE.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 liquid-column-6a04b18dd4b33\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"  ><div class=\"wpb_wrapper-inner\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><style>@media (min-width: 1200px) { .liquid-row-responsive-6a04b18dd5f05 {margin-bottom:30px !important;  }  }   <\/style><section class=\"vc_row wpb_row vc_row-fluid vc_custom_1701693271637 liquid-row-responsive-6a04b18dd5f05 liquid-row-shadowbox-6a04b18dd5f16 vc_column-gap-35\"><div class=\"ld-container container\"><div class=\"row ld-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 liquid-column-6a04b18dd6173\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"   ><div class=\"wpb_wrapper-inner\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1748945720731\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p class=\"p2\"><span class=\"s2\" style=\"color: #f0f0f0;\"><b>WHEN WILL THEY TAKE PLACE<\/b><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1678275937565 liquid-row-shadowbox-6a04b18dd6346\"><div class=\"wpb_column vc_column_container vc_col-sm-12 liquid-column-6a04b18dd6537\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"  ><div class=\"wpb_wrapper-inner\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<ul>\n<li class=\"v1MsoNormal\">First camp: From 22nd of June to the 5th of July (children between the ages of 7-12)<\/li>\n<li class=\"v1MsoNormal\">Second camp: From the 14th to the 27th of July (Children between the ages of 7-12)<\/li>\n<li class=\"v1MsoNormal\">Third camp: From the 31st of July to the 13th of August. (Children between the ages of 9-14)<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"vc_row wpb_row vc_row-fluid liquid-row-shadowbox-6a04b18dd696a vc_column-gap-35\"><div class=\"ld-container container\"><div class=\"row ld-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 liquid-column-6a04b18dd6bc5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"   ><div class=\"wpb_wrapper-inner\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1748945776072\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p class=\"p2\"><span class=\"s2\" style=\"color: #f0f0f0;\"><b>WHAT WE OFFER<\/b><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid liquid-row-shadowbox-6a04b18dd6e44 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-6 liquid-column-6a04b18dd74b2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"  ><div class=\"wpb_wrapper-inner\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left  liquid_vc_single_image-6a04b18de3bf2\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" width=\"1440\" height=\"1110\" src=\"data:image\/svg+xml;charset=utf-8,&lt;svg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1440 1110&#039;%2F&gt;\" class=\"vc_single_image-img attachment-full ld-lazyload\" alt=\"\" title=\"20250810_173050_resultado\" srcset=\"\" sizes=\"(max-width: 1440px) 100vw, 1440px\" data-src=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/20250810_173050_resultado-e1773999501448.jpg\" data-srcset=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/20250810_173050_resultado-e1773999501448.jpg 1440w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/20250810_173050_resultado-e1773999501448-300x231.jpg 300w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/20250810_173050_resultado-e1773999501448-1024x789.jpg 1024w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/20250810_173050_resultado-e1773999501448-16x12.jpg 16w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/20250810_173050_resultado-e1773999501448-768x592.jpg 768w\" data-aspect=\"1.2972972972973\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 liquid-column-6a04b18de3e0a\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"  ><div class=\"wpb_wrapper-inner\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Shared life experience<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Development of autonomy and personal skills, in an atmospehere of respect and freedom.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Care and practice of healthy habits: nutrition, hygiene and physical activity.<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid liquid-row-shadowbox-6a04b18de4016 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-6 liquid-column-6a04b18de419b\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"  ><div class=\"wpb_wrapper-inner\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Games which aswell as being fun promote participation and cooperation.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Workshops that encourage creativity, artistic freedom and aesthetic education.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Routes and walks in the surrounding area to discover the landcsape, the local flora and fauna.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Science workshops: Experiments.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Folklore and popular culture: songbook and traditional games.<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 liquid-column-6a04b18de439d\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"  ><div class=\"wpb_wrapper-inner\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left  liquid_vc_single_image-6a04b18deca59\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" width=\"1209\" height=\"1494\" src=\"data:image\/svg+xml;charset=utf-8,&lt;svg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1209 1494&#039;%2F&gt;\" class=\"vc_single_image-img attachment-full ld-lazyload\" alt=\"\" title=\"IMG-20250802-0051\" srcset=\"\" sizes=\"(max-width: 1209px) 100vw, 1209px\" data-src=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/IMG-20250802-0051-e1773999561356.jpg\" data-srcset=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/IMG-20250802-0051-e1773999561356.jpg 1209w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/IMG-20250802-0051-e1773999561356-243x300.jpg 243w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/IMG-20250802-0051-e1773999561356-829x1024.jpg 829w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/IMG-20250802-0051-e1773999561356-10x12.jpg 10w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/IMG-20250802-0051-e1773999561356-768x949.jpg 768w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/IMG-20250802-0051-e1773999561356-1024x1265.jpg 1024w\" data-aspect=\"0.80923694779116\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid liquid-row-shadowbox-6a04b18decbf4 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-6 liquid-column-6a04b18decdb7\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"  ><div class=\"wpb_wrapper-inner\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left  liquid_vc_single_image-6a04b18df2d22\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" width=\"1440\" height=\"1133\" src=\"data:image\/svg+xml;charset=utf-8,&lt;svg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1440 1133&#039;%2F&gt;\" class=\"vc_single_image-img attachment-full ld-lazyload\" alt=\"\" title=\"20250627_123103_resultado\" srcset=\"\" sizes=\"(max-width: 1440px) 100vw, 1440px\" data-src=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/20250627_123103_resultado-e1773999637258.jpg\" data-srcset=\"https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/20250627_123103_resultado-e1773999637258.jpg 1440w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/20250627_123103_resultado-e1773999637258-300x236.jpg 300w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/20250627_123103_resultado-e1773999637258-1024x806.jpg 1024w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/20250627_123103_resultado-e1773999637258-15x12.jpg 15w, https:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/20250627_123103_resultado-e1773999637258-768x604.jpg 768w\" data-aspect=\"1.2709620476611\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 liquid-column-6a04b18df2f13\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"  ><div class=\"wpb_wrapper-inner\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Excursions to the beach and historical places.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Making a personal diary as a reflection and memory of the activities.<br \/>\nLibrary of the camp: personal and shared readings.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">The  theatre as a way of learning: dramatic expression.<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Small groups<\/span><\/p>\n<p><span style=\"font-weight: 400;\">One teacher for every 6 children<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Reservation of places open<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section><style>@media (min-width: 1200px) { .liquid-row-responsive-6a04b18df339e {margin-top:30px !important;  }  }   <\/style><section data-bg-image=\"url\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1701695709975 row-contains-padding-top row-contains-padding-bottom liquid-row-responsive-6a04b18df339e liquid-row-shadowbox-6a04b18df33b0 vc_row-has-fill vc_row-has-bg\"><div class=\"ld-container container\"><div class=\"row ld-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 liquid-column-6a04b18df3576\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"   ><div class=\"wpb_wrapper-inner\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1678276949539\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>MORE INFORMATION AND REGISTRATION<\/strong><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1748945939154\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Silvia Basanta and Itziar Diaz-Delgado<br \/>\n<strong>Phones:<\/strong> <span style=\"font-weight: 400;\">(+34) 626 682 218 \/\u00a0 914 119 714<\/span><br \/>\n<strong>Email:<\/strong> <a href=\"mailto:colonias@fundacionginer.org\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">colonias@fundacionginer.org<\/span><\/a><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<a href=\"http:\/\/prueba.fundacionginer.org\/wp-content\/uploads\/2026\/03\/colonias_verano_26_ok.pdf\" target=\"_blank\" class=\"btn btn-default btn-md btn-bordered border-thin btn-icon-left ld_button_6a04b18df36f2 vc_custom_1773999212797\">\n\t<span>\n\t\t\n\t\t\t\t\t<span class=\"btn-txt\">More information<\/span>\n\t\t\t\n\t<span class=\"btn-icon\"><i class=\"\"><\/i><\/span>\t\t\t<\/span>\n<\/a>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n<\/div>","protected":false},"featured_media":13068,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[115,113],"tags":[77],"class_list":["post-13067","actividades","type-actividades","status-publish","format-standard","has-post-thumbnail","hentry","category-colonias-de-verano","category-naturaleza","tag-actuales"],"acf":[],"_links":{"self":[{"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/actividades\/13067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/actividades"}],"about":[{"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/types\/actividades"}],"version-history":[{"count":11,"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/actividades\/13067\/revisions"}],"predecessor-version":[{"id":13083,"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/actividades\/13067\/revisions\/13083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/media\/13068"}],"wp:attachment":[{"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/media?parent=13067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/categories?post=13067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prueba.fundacionginer.org\/en\/wp-json\/wp\/v2\/tags?post=13067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}